{"id":11552,"date":"2024-06-27T06:28:09","date_gmt":"2024-06-27T06:28:09","guid":{"rendered":"http:\/\/localhost\/agency\/?page_id=11552"},"modified":"2026-02-16T14:52:49","modified_gmt":"2026-02-16T14:52:49","slug":"contact","status":"publish","type":"page","link":"https:\/\/themesold.com\/apar\/tbt\/vipevent\/contact\/","title":{"rendered":"Contact"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"11552\" class=\"elementor elementor-11552\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5eafc63 e-flex e-con-boxed e-con e-parent\" data-id=\"5eafc63\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-57170b4 elementor-widget elementor-widget-tts\" data-id=\"57170b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tts.default\">\n\t\t\t\t\t\t\t\t\t\t<!-- title center -->\n\t\t\t\t\t<div class=\"tts text-center\">\n\t\t\t\t\t\t<div class=\"ttin\">\n\n\t\t\t\t\t\t\t<!-- icon position -->\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<!-- image -->\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<!-- icon -->\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<!-- bar -->\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<!-- circle bar -->\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<!-- end icon position -->\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<!-- title top -->\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"txbdstitle tsmall stone hlight txbdbcolor \">Get In Touch <\/h4>\t\t\n\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t<!-- icon position -->\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<!-- end icon position -->\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<!-- title middle -->\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"txbdstitle sttwo hlight\">Have Any Question?<\/h2>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<!-- title bottom -->\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<!-- content -->\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<!-- inner title -->\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55bb20b vipevent-star-rating--align-center elementor-widget elementor-widget-witr_section_apartment\" data-id=\"55bb20b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"witr_section_apartment.default\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"apartment_area\">\t\t\t\t\n\t\t\t\t\t\t<div class=\"apartment_text\">\t\t\n\t\t\t\t\t\t\t<!-- title -->\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<!-- content -->\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\t\t\n\t\t\t\t\t\t<div class=\"witr_apartment_form\">\t\t\t\t\t\n\t\t\t\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f22637-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"22637\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/apar\/tbt\/vipevent\/wp-json\/wp\/v2\/pages\/11552#wpcf7-f22637-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"22637\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f22637-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"row\">\n\t<div class=\"col-lg-6 col-md-6\">\n\t\t<div class=\"twr_form_box\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"text-30\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required form-control\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Name*\" value=\"\" type=\"text\" name=\"text-30\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"col-lg-6 col-md-6\">\n\t\t<div class=\"twr_form_box\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"email-380\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email form-control\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email*\" value=\"\" type=\"email\" name=\"email-380\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"col-lg-12 col-md-12\">\n\t\t<div class=\"twr_form_box\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"number-11\"><input class=\"wpcf7-form-control wpcf7-number wpcf7-validates-as-required wpcf7-validates-as-number form-control\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Phone*\" value=\"\" type=\"number\" name=\"number-11\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"col-lg-12 col-md-12\">\n\t\t<div class=\"twr_form_box \">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"textarea\"><textarea cols=\"40\" rows=\"6\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required form-control\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Text Message*\" name=\"textarea\"><\/textarea><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\" text\">\n\t\t\t<p><button type=\"submit\" class=\"btn btn-primary\">Send Message<\/button>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f32e72d e-con-full e-flex e-con e-parent\" data-id=\"f32e72d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-021d14e elementor-widget elementor-widget-google_maps\" data-id=\"021d14e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=Dkaka&#038;t=m&#038;z=10&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"Dkaka\"\n\t\t\t\t\taria-label=\"Dkaka\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Get In Touch Have Any Question? Send Message<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-home.php","meta":{"footnotes":""},"class_list":["post-11552","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/themesold.com\/apar\/tbt\/vipevent\/wp-json\/wp\/v2\/pages\/11552","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/themesold.com\/apar\/tbt\/vipevent\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/themesold.com\/apar\/tbt\/vipevent\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/themesold.com\/apar\/tbt\/vipevent\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/themesold.com\/apar\/tbt\/vipevent\/wp-json\/wp\/v2\/comments?post=11552"}],"version-history":[{"count":0,"href":"https:\/\/themesold.com\/apar\/tbt\/vipevent\/wp-json\/wp\/v2\/pages\/11552\/revisions"}],"wp:attachment":[{"href":"https:\/\/themesold.com\/apar\/tbt\/vipevent\/wp-json\/wp\/v2\/media?parent=11552"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}